{"id":979,"count":1,"description":"","link":"https:\/\/moroccopreneur.com\/en\/label\/endeavor-global-network\/","name":"Endeavor Global Network","slug":"endeavor-global-network","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Endeavor Global Network - Moroccopreneur<\/title>\n<meta name=\"description\" content=\"Moroccopreneur is a digital content platform about &quot;Morocco that inspires and Moroccans who aspire&quot;\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Endeavor Global Network\" \/>\n<meta property=\"og:description\" content=\"Moroccopreneur is a digital content platform about &quot;Morocco that inspires and Moroccans who aspire&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moroccopreneur.com\/en\/label\/endeavor-global-network\/\" \/>\n<meta property=\"og:site_name\" content=\"Moroccopreneur\" \/>\n<meta property=\"og:image\" content=\"https:\/\/moroccopreneur.com\/wp-content\/uploads\/2023\/03\/Morocco-that-inspires-Moroccans-who-aspire.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Moroccopreneur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/label\\\/endeavor-global-network\\\/\",\"url\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/label\\\/endeavor-global-network\\\/\",\"name\":\"Endeavor Global Network - Moroccopreneur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/#website\"},\"description\":\"Moroccopreneur is a digital content platform about \\\"Morocco that inspires and Moroccans who aspire\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/label\\\/endeavor-global-network\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/label\\\/endeavor-global-network\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Moroccopreneur\",\"item\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Endeavor Global Network\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/\",\"name\":\"Moroccopreneur\",\"description\":\"Inspiring Morocco, Aspiring Moroccans\",\"publisher\":{\"@id\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/#organization\",\"name\":\"Moroccopreneur\",\"url\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/moroccopreneur.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-Moroccopreneur-Logo-2023-Solo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/moroccopreneur.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-Moroccopreneur-Logo-2023-Solo-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Moroccopreneur\"},\"image\":{\"@id\":\"https:\\\/\\\/moroccopreneur.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Moroccopreneur\",\"https:\\\/\\\/x.com\\\/Moroccopreneur\",\"https:\\\/\\\/www.instagram.com\\\/moroccopreneur\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/moroccopreneur\",\"https:\\\/\\\/www.pinterest.com\\\/moroccopreneur\",\"https:\\\/\\\/www.youtube.com\\\/@moroccopreneur\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Endeavor Global Network - Moroccopreneur","description":"Moroccopreneur is a digital content platform about \"Morocco that inspires and Moroccans who aspire\"","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Endeavor Global Network","og_description":"Moroccopreneur is a digital content platform about \"Morocco that inspires and Moroccans who aspire\"","og_url":"https:\/\/moroccopreneur.com\/en\/label\/endeavor-global-network\/","og_site_name":"Moroccopreneur","og_image":[{"width":2560,"height":1440,"url":"https:\/\/moroccopreneur.com\/wp-content\/uploads\/2023\/03\/Morocco-that-inspires-Moroccans-who-aspire.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Moroccopreneur","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/moroccopreneur.com\/en\/label\/endeavor-global-network\/","url":"https:\/\/moroccopreneur.com\/en\/label\/endeavor-global-network\/","name":"Endeavor Global Network - Moroccopreneur","isPartOf":{"@id":"https:\/\/moroccopreneur.com\/en\/#website"},"description":"Moroccopreneur is a digital content platform about \"Morocco that inspires and Moroccans who aspire\"","breadcrumb":{"@id":"https:\/\/moroccopreneur.com\/en\/label\/endeavor-global-network\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/moroccopreneur.com\/en\/label\/endeavor-global-network\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Moroccopreneur","item":"https:\/\/moroccopreneur.com\/en\/"},{"@type":"ListItem","position":2,"name":"Endeavor Global Network"}]},{"@type":"WebSite","@id":"https:\/\/moroccopreneur.com\/en\/#website","url":"https:\/\/moroccopreneur.com\/en\/","name":"Moroccopreneur","description":"Inspiring Morocco, Aspiring Moroccans","publisher":{"@id":"https:\/\/moroccopreneur.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moroccopreneur.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/moroccopreneur.com\/en\/#organization","name":"Moroccopreneur","url":"https:\/\/moroccopreneur.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/moroccopreneur.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/moroccopreneur.com\/wp-content\/uploads\/2023\/02\/cropped-Moroccopreneur-Logo-2023-Solo-1.jpg","contentUrl":"https:\/\/moroccopreneur.com\/wp-content\/uploads\/2023\/02\/cropped-Moroccopreneur-Logo-2023-Solo-1.jpg","width":512,"height":512,"caption":"Moroccopreneur"},"image":{"@id":"https:\/\/moroccopreneur.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Moroccopreneur","https:\/\/x.com\/Moroccopreneur","https:\/\/www.instagram.com\/moroccopreneur\/","https:\/\/www.linkedin.com\/company\/moroccopreneur","https:\/\/www.pinterest.com\/moroccopreneur","https:\/\/www.youtube.com\/@moroccopreneur"]}]}},"_links":{"self":[{"href":"https:\/\/moroccopreneur.com\/en\/wp-json\/wp\/v2\/tags\/979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moroccopreneur.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/moroccopreneur.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/moroccopreneur.com\/en\/wp-json\/wp\/v2\/posts?tags=979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}